




{"id":6415,"date":"2025-10-22T14:41:12","date_gmt":"2025-10-22T12:41:12","guid":{"rendered":"https:\/\/montagnac.com\/?post_type=product&#038;p=6415"},"modified":"2026-09-02T17:51:40","modified_gmt":"2026-09-02T16:51:40","slug":"chateau-potensac-2022","status":"publish","type":"product","link":"https:\/\/montagnac.com\/en\/product\/chateau-potensac-2022\/","title":{"rendered":"Ch\u00e2teau Potensac 2022"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td>Fruit\u00e9<\/td>\n<td><div class=\"progress_icons  transparent\" data-active=\"5\" data-color=\"\"><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><\/div>\n<\/td>\n<td>\u00c9pic\u00e9\/Bois\u00e9<\/td>\n<td><div class=\"progress_icons  transparent\" data-active=\"4\" data-color=\"\"><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>Floral<\/td>\n<td><div class=\"progress_icons  transparent\" data-active=\"3\" data-color=\"\"><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><\/div>\n<\/td>\n<td>Min\u00e9ral<\/td>\n<td><div class=\"progress_icons  transparent\" data-active=\"4\" data-color=\"\"><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><span class=\"progress_icon\" style=\"\"><i class=\"fas fa-circle\"><\/i><\/span><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Consid\u00e9r\u00e9 comme l&rsquo;un des meilleurs mill\u00e9simes de la propri\u00e9t\u00e9, ce 2022 est un M\u00e9doc pur et puissant. Il d\u00e9voile des ar\u00f4mes intenses de cassis, de menthe et d&rsquo;iode, avec une texture caressante et des tanins d&rsquo;une grande finesse. Un vin de caract\u00e8re, taill\u00e9 pour la garde, qui repr\u00e9sente une valeur s\u00fbre de l&rsquo;appellation.<\/p>","protected":false},"featured_media":6421,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[223],"product_cat":[670,677],"product_tag":[928,926],"class_list":["post-6415","product","type-product","status-publish","has-post-thumbnail","product_brand-chateau-potensac","product_cat-bordeaux","product_cat-haut-medoc-medoc","product_tag-puissant-tannique","product_tag-vins-de-garde","pa_appellation-medoc-aoc","pa_conditionnement-1x75cl","pa_conditionnement-caisse-bois-de-6-bouteilles-75","pa_couleur-rouge","pa_format-75cl","pa_millesime-770","pa_region-bordeaux","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/product\/6415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/comments?post=6415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/media\/6421"}],"wp:attachment":[{"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/media?parent=6415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/product_brand?post=6415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/product_cat?post=6415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/montagnac.com\/en\/wp-json\/wp\/v2\/product_tag?post=6415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}